{"id":526,"date":"2022-10-26T13:07:12","date_gmt":"2022-10-26T11:07:12","guid":{"rendered":"https:\/\/gecoo.eu\/coopedil\/?page_id=526"},"modified":"2023-05-11T12:23:23","modified_gmt":"2023-05-11T10:23:23","slug":"progetto","status":"publish","type":"page","link":"https:\/\/ambientecooperative.it\/infernetto-nord\/progetto\/","title":{"rendered":"Progetto"},"content":{"rendered":"<section class=\"l-section wpb_row us_custom_68ec3198 height_medium with_img\"><div class=\"l-section-img\" data-img-width=\"1234\" data-img-height=\"307\" style=\"background-image: url(https:\/\/ambientecooperative.it\/infernetto-nord\/wp-content\/uploads\/sites\/3\/2022\/09\/cantiere-infernetto-2.jpg);background-position: top center;background-repeat: no-repeat;\"><\/div><div class=\"l-section-overlay\" style=\"background:rgba(51,51,51,0.55)\"><\/div><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\">[vc_custom_heading text=&#8221;NUOVE COSTRUZIONI &#8211; ZONA INFERNETTO ROMA&#8221; font_container=&#8221;tag:h1|font_size:43|text_align:center|color:%23ffffff&#8221; google_fonts=&#8221;font_family:Alef%3Aregular%2C700|font_style:400%20regular%3A400%3Anormal&#8221; css=&#8221;%7B%22default%22%3A%7B%22color%22%3A%22%23ffffff%22%7D%7D&#8221;][vc_custom_heading text=&#8221;Via Alberto Franchetti&#8221; font_container=&#8221;tag:h4|font_size:28|text_align:center|color:%236b6b6b&#8221; google_fonts=&#8221;font_family:Abel%3Aregular|font_style:400%20regular%3A400%3Anormal&#8221; css=&#8221;%7B%22default%22%3A%7B%22color%22%3A%22%23e8e8e8%22%2C%22margin-top%22%3A%22-40px%22%7D%7D&#8221;]<\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_2-1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><div id=\"wpgmza_map\" class=\"wpgmza_map\" data-settings='{\"id\":\"1\",\"map_title\":\"La mia prima mappa\",\"map_width\":\"100\",\"map_height\":\"360\",\"map_start_lat\":\"41.75631312117768\",\"map_start_lng\":\"12.376430207241933\",\"map_start_location\":\"45.950464398418106,-109.81550500000003\",\"map_start_zoom\":\"14\",\"default_marker\":\"\",\"type\":\"3\",\"alignment\":\"4\",\"directions_enabled\":\"0\",\"styling_enabled\":\"0\",\"styling_json\":\"\",\"active\":\"0\",\"kml\":\"\",\"bicycle\":\"0\",\"traffic\":\"0\",\"dbox\":\"0\",\"dbox_width\":\"\",\"listmarkers\":\"0\",\"listmarkers_advanced\":\"0\",\"filterbycat\":\"0\",\"ugm_enabled\":\"0\",\"ugm_category_enabled\":\"0\",\"fusion\":\"\",\"map_width_type\":\"%\",\"map_height_type\":\"px\",\"mass_marker_support\":\"0\",\"ugm_access\":\"0\",\"order_markers_by\":\"0\",\"order_markers_choice\":\"0\",\"show_user_location\":\"0\",\"default_to\":\"\",\"other_settings\":{\"map_type\":1,\"sl_stroke_color\":\"\",\"sl_fill_color\":\"\",\"sl_stroke_opacity\":\"\",\"sl_fill_opacity\":\"\",\"transport_layer\":false,\"action\":\"wpgmza_save_map\",\"redirect_to\":\"\\\/infernetto-nord\\\/wp-admin\\\/admin-post.php\",\"map_id\":\"1\",\"http_referer\":\"\\\/infernetto-nord\\\/wp-admin\\\/admin.php?page=wp-google-maps-menu&amp;amp;action=edit&amp;amp;map_id=1\",\"wpgmza_id\":\"1\",\"wpgmza_start_location\":\"41.75631312117768,12.376430207241933\",\"wpgmza_start_zoom\":\"14\",\"wpgmza_theme_data\":\"\",\"store_locator_enabled\":false,\"store_locator_search_area\":\"radial\",\"wpgmza_store_locator_radius_style\":\"legacy\",\"wpgmza_store_locator_default_radius\":\"10\",\"store_locator_auto_area_max_zoom\":\"\",\"store_locator_distance\":false,\"wpgmza_store_locator_position\":false,\"store_locator_show_distance\":false,\"store_locator_category\":false,\"wpgmza_store_locator_use_their_location\":false,\"wpgmza_store_locator_bounce\":false,\"wpgmza_sl_animation\":null,\"wpgmza_store_locator_hide_before_search\":false,\"store_locator_query_string\":\"\",\"store_locator_location_placeholder\":\"\",\"store_locator_default_address\":\"\",\"store_locator_name_search\":false,\"store_locator_name_string\":\"\",\"store_locator_not_found_message\":\"\",\"wpgmza_map_align\":\"1\",\"jump_to_nearest_marker_on_initialization\":false,\"automatically_pan_to_users_location\":false,\"override_users_location_zoom_level\":false,\"override_users_location_zoom_levels\":\"\",\"show_distance_from_location\":false,\"map_max_zoom\":\"21\",\"map_min_zoom\":\"0\",\"click_open_link\":false,\"fit_maps_bounds_to_markers\":false,\"fit_maps_bounds_to_markers_after_filtering\":false,\"hide_point_of_interest\":false,\"wpgmza_zoom_on_marker_click\":false,\"wpgmza_zoom_on_marker_click_slider\":\"\",\"close_infowindow_on_map_click\":false,\"disable_lightbox_images\":false,\"use_Raw_Jpeg_Coordinates\":false,\"polygon_labels\":false,\"disable_polygon_info_windows\":false,\"enable_marker_ratings\":false,\"only_load_markers_within_viewport\":false,\"iw_primary_color\":\"#000000\",\"iw_accent_color\":\"#000000\",\"iw_text_color\":\"#000000\",\"wpgmza_listmarkers_by\":\"0\",\"wpgmza_marker_listing_position\":false,\"wpgmza_push_in_map\":false,\"wpgmza_push_in_map_placement\":null,\"wpgmza_push_in_map_width\":\"\",\"wpgmza_push_in_map_height\":\"\",\"zoom_level_on_marker_listing_override\":false,\"zoom_level_on_marker_listing_click\":\"\",\"marker_listing_disable_zoom\":false,\"datatable_no_result_message\":\"\",\"remove_search_box_datables\":false,\"dataTable_pagination_style\":null,\"datatable_search_string\":\"\",\"datatable_result_start\":\"\",\"datatable_result_of\":\"\",\"datatable_result_to\":\"\",\"datatable_result_total\":\"\",\"datatable_result_show\":\"\",\"datatable_result_entries\":\"\",\"wpgmza_savemap\":\"Salva la Mappa \\u00bb\"}}' data-map-id='1' Data-maps-engine='google-maps' data-shortcode-attributes='{\"id\":\"1\"}' style=\"display:block; overflow:auto; width:100%; height:360px; float:left;\"><\/div>\n<\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\">[vc_custom_heading text=&#8221;Il Piano di Zona Infernetto Nord si attesta nell\u2019ultima area libera prima del settore settentrionale della tenuta presidenziale di Castel Porziano, in una zona di particolare interesse ambientale aderente alla via Cristoforo Colombo.&#8221; font_container=&#8221;tag:h4|font_size:22|text_align:left&#8221; google_fonts=&#8221;font_family:Abel%3Aregular|font_style:400%20regular%3A400%3Anormal&#8221;]<\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium color_alternate\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_1 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\">[vc_custom_heading text=&#8221;Il progetto \u00e8 inserito all\u2019interno del Piano di Zona B60 \u201cInfernetto Nord Bis\u201d<br \/>\n, gi\u00e0 autorizzato dalla Regione Lazio in fase di approvazione del piano (Parere Paesaggistico Prot. n.110196 del 4 agosto 2010 \u2013 All. n.2) e di approvazione delle opere di urbanizzazione in Conferenza dei Servizi (Parere favorevole recepito con chiusura CdS in data 23 settembre 2021). La Convenzione Integrativa per la realizzazione delle OOUU a scomputo degli oneri concessori \u00e8 stata sottoscritta in data 5\/5\/2022 a rogito notaio Centini di Roma (rep.2104-racc.1686). Il piano approvato ha previsto l\u2019inserimento di una fascia di rispetto dalla via Cristoforo Colombo di circa 40 ml dal ciglio stradale, da destinare a verde pubblico naturale ed attrezzato con lo scopo di mitigare l\u2019impatto visuale del complesso verso gli utenti che percorrono la via Cristoforo Colombo ed allo stesso tempo mitigare l\u2019impatto acustico del traffico veicolare nei confronti degli utenti dei complessi edilizi del piano stesso.&#8221; font_container=&#8221;tag:p|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221;]<\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_2 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\">[vc_custom_heading text=&#8221;Il progetto edilizio ( protocollo Comune di Roma QI\/2021\/61734 e Nuovi Tipi QI\/2022\/126436) prevede la realizzazione nel comparto B2, di n. 2 palazzine ognuna<br \/>\ncontenente 12 unit\u00e0 abitative disposte su quattro piani fuori terra, all&#8217;interno del perimetro di massimo ingombro consentito, per complessivi 6130,36 mc f.t. e1893,76 di SUL al di sotto della cubatura massima assegnata di 6160,00 e della corrispondente Sul max assentibile&#8221; font_container=&#8221;tag:p|font_size:20|text_align:left|color:%230a0a0a&#8221; google_fonts=&#8221;font_family:Abel%3Aregular|font_style:400%20regular%3A400%3Anormal&#8221;]<\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-image align_center\"><div class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"515\" src=\"https:\/\/ambientecooperative.it\/infernetto-nord\/wp-content\/uploads\/sites\/3\/2022\/08\/2-inclinata-fg-1-1024x515.png\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ambientecooperative.it\/infernetto-nord\/wp-content\/uploads\/sites\/3\/2022\/08\/2-inclinata-fg-1-1024x515.png 1024w, https:\/\/ambientecooperative.it\/infernetto-nord\/wp-content\/uploads\/sites\/3\/2022\/08\/2-inclinata-fg-1-300x151.png 300w, https:\/\/ambientecooperative.it\/infernetto-nord\/wp-content\/uploads\/sites\/3\/2022\/08\/2-inclinata-fg-1-600x301.png 600w, https:\/\/ambientecooperative.it\/infernetto-nord\/wp-content\/uploads\/sites\/3\/2022\/08\/2-inclinata-fg-1.png 1419w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><div class=\"w-separator size_medium with_line width_default thick_1 style_solid color_border align_center\"><div class=\"w-separator-h\"><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium color_primary\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_2 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-image align_center\"><div class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"691\" src=\"https:\/\/ambientecooperative.it\/infernetto-nord\/wp-content\/uploads\/sites\/3\/2022\/10\/alto-1024x691.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ambientecooperative.it\/infernetto-nord\/wp-content\/uploads\/sites\/3\/2022\/10\/alto-1024x691.jpg 1024w, https:\/\/ambientecooperative.it\/infernetto-nord\/wp-content\/uploads\/sites\/3\/2022\/10\/alto-300x202.jpg 300w, https:\/\/ambientecooperative.it\/infernetto-nord\/wp-content\/uploads\/sites\/3\/2022\/10\/alto-593x400.jpg 593w, https:\/\/ambientecooperative.it\/infernetto-nord\/wp-content\/uploads\/sites\/3\/2022\/10\/alto.jpg 1134w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><div class=\"w-separator size_medium with_line width_default thick_1 style_solid color_border align_center\"><div class=\"w-separator-h\"><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\">[vc_custom_heading text=&#8221;Gli spazi esterni condominiali sono armonizzati con gli spazi condominiali limitrofi (comparti B1 e B3 ) e gli spazio pubblici stradali circostanti con sistemazioni a verde di raccordo con la quota dei marciapiedi coerenti con la quota dei piani terra impostata almeno a +27,30 m.s.m. come da prescrizioni per la sicurezza idraulica. Grande attenzione \u00e8 stata posta nel progetto alla sistemazione delle aree comuni e degli spazi aperti tra gli edifici in particolare nell\u2019organizzazione dei percorsi pedonali, minimizzando quelli carrabili, garantendo pi\u00f9 accessi pedonali, anche dal verde pubblico adiacente, e nella scelta delle essenze arboree ed arbustive.&#8221; font_container=&#8221;tag:p|font_size:20|text_align:left|color:%23ffffff&#8221; google_fonts=&#8221;font_family:Abel%3Aregular|font_style:400%20regular%3A400%3Anormal&#8221;]<\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_2 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\">[vc_custom_heading text=&#8221;Secondo le norme del Piano di Zona, il progetto prevede la messa a dimora di 13 alberi ad alto fusto e 25arbusti, entrambe in quantit\u00e0 maggiore della dotazione minima pari a 12 esemplari di alberi e 21 di arbusti (art.18 comma 2 NTA &#8211; P.d.Z.). Le essenze individuate rispettano le caratteristiche paesaggistiche e le preesistenze della zona e sono state scelte secondo i criteri del \u201cRegolamento del verde pubblico e privato e del paesaggio urbano di Roma Capitale\u201d. In particolare si \u00e8 optato per l\u2019inserimento di alberi ed arbusti tipici della zona meridionale dell\u2019Europa con una vasta gamma di colori del fogliame e della fioritura tra cui alberi caducifoglie (Prunus Cerasifera Pissardi, Acer monspessulanum e Pyrus calleryna chanticleer) ed arbusti (Prunus laurocerasus e Viburnum tinus) .&#8221; font_container=&#8221;tag:p|font_size:20|text_align:left|color:%230a0a0a&#8221; google_fonts=&#8221;font_family:Abel%3Aregular|font_style:400%20regular%3A400%3Anormal&#8221;]<\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-image align_center\"><div class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"339\" src=\"https:\/\/ambientecooperative.it\/infernetto-nord\/wp-content\/uploads\/sites\/3\/2022\/10\/1-1024x339.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ambientecooperative.it\/infernetto-nord\/wp-content\/uploads\/sites\/3\/2022\/10\/1-1024x339.jpg 1024w, https:\/\/ambientecooperative.it\/infernetto-nord\/wp-content\/uploads\/sites\/3\/2022\/10\/1-300x99.jpg 300w, https:\/\/ambientecooperative.it\/infernetto-nord\/wp-content\/uploads\/sites\/3\/2022\/10\/1-600x199.jpg 600w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><div class=\"w-separator size_medium with_line width_default thick_1 style_solid color_border align_center\"><div class=\"w-separator-h\"><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_951d56c7 height_medium color_primary\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_2 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-image align_center\"><div class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"704\" src=\"https:\/\/ambientecooperative.it\/infernetto-nord\/wp-content\/uploads\/sites\/3\/2022\/10\/planivolumetrico-1024x704.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ambientecooperative.it\/infernetto-nord\/wp-content\/uploads\/sites\/3\/2022\/10\/planivolumetrico-1024x704.jpg 1024w, https:\/\/ambientecooperative.it\/infernetto-nord\/wp-content\/uploads\/sites\/3\/2022\/10\/planivolumetrico-300x206.jpg 300w, https:\/\/ambientecooperative.it\/infernetto-nord\/wp-content\/uploads\/sites\/3\/2022\/10\/planivolumetrico-582x400.jpg 582w, https:\/\/ambientecooperative.it\/infernetto-nord\/wp-content\/uploads\/sites\/3\/2022\/10\/planivolumetrico.jpg 1386w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><div class=\"w-separator size_medium with_line width_default thick_1 style_solid color_border align_center\"><div class=\"w-separator-h\"><\/div><\/div><\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\">[vc_custom_heading text=&#8221;La sistemazione delle pavimentazioni esterne verr\u00e0 realizzata in parte con sistemazione a giardino e in parte con pavimentazioni drenanti in modo da garantire il giusto rapporto tra superfice permeabile e superficie impermeabile del lotto pari ad almeno il 50% della superficie fondiaria (art.18 comma 1 NTA &#8211; P.d.Z.). Per le pavimentazioni drenanti le finiture saranno in continuit\u00e0 con la pavimentazione degli spazi pubblici, in particolare con betonelle in calcestruzzo con colorazioni sui toni delle \u201cterre naturali\u201d secondo le disponibilit\u00e0 in commercio. Gli edifici, avranno struttura portante in cemento armato, solai in latero cemento e tamponatura in laterizio e\/o c.a alleggerito. La morfologia inclinata delle pareti verticali \u00e8 determinata dalla sovrapposizione libera delle tipologie edilizie, quella della copertura, dall\u2019 inserimento dei pannelli solari per la produzione dell\u2019acqua sanitaria e degli elementi fotovoltaici collocati in modo da garantire il massimo sfruttamento della superfici captanti, e soddisfare i requisiti per la produzione di energia da fonti rinnovabili, come previsto dalle norme vigenti. L\u2019inserimento integrato architettonicamente nella morfologia degli edifici \u00e8 cos\u00ec significativo da determinarne il profilo.&#8221; font_container=&#8221;tag:p|font_size:18|text_align:left|color:%23ffffff&#8221; google_fonts=&#8221;font_family:Abel%3Aregular|font_style:400%20regular%3A400%3Anormal&#8221;]<\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_grid cols_2 laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\"><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\">[vc_custom_heading text=&#8221;Gli impianti accessori quali boiler per l\u2019accumulo dell\u2019acqua calda e inverter di accumulo dell\u2019energia elettrica prodotta, saranno collocati all\u2019interno dei vani accessori collocati al piano servizi degli edifici, nascosti alla vista dall\u2019esterno Particolare attenzione sar\u00e0 prestata alla uniformit\u00e0 dei manufatti di recinzione tra i comparti e le aree pubbliche Saranno utilizzate finiture in travertino chiaro per imbotti, soglie di finestre e porte finestre, copertine dei muretti di recinzione. Le tinteggiature delle murature di tamponamento e\/o delle pareti in c.a saranno dai colori neutri chiari in armonia con le finiture degli edifici limitrofi con cui si operer\u00e0 un coordinamento progettuale per i trattamenti superficiali. Gli infissi esterni saranno in PVC o alluminio con finitura esterna effetto legno naturale finitura rovere . Le serrande avranno colori chiari. I parcheggi pertinenziali sono stati reperiti al livello interrato per una superficie complessiva di 683,0 mq. &gt; 616,0 mq. richiesti per la volumetria residenziale, in modo da non impattare visivamente ed ingombrare le aree esterne agli edifici.&#8221; font_container=&#8221;tag:p|font_size:18|text_align:left&#8221; use_theme_fonts=&#8221;yes&#8221;]<\/div><\/div><div class=\"wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"w-image align_center\"><div class=\"w-image-h\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"704\" src=\"https:\/\/ambientecooperative.it\/infernetto-nord\/wp-content\/uploads\/sites\/3\/2022\/10\/planivolumetrico-esec-1024x704.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/ambientecooperative.it\/infernetto-nord\/wp-content\/uploads\/sites\/3\/2022\/10\/planivolumetrico-esec-1024x704.jpg 1024w, https:\/\/ambientecooperative.it\/infernetto-nord\/wp-content\/uploads\/sites\/3\/2022\/10\/planivolumetrico-esec-300x206.jpg 300w, https:\/\/ambientecooperative.it\/infernetto-nord\/wp-content\/uploads\/sites\/3\/2022\/10\/planivolumetrico-esec-582x400.jpg 582w, https:\/\/ambientecooperative.it\/infernetto-nord\/wp-content\/uploads\/sites\/3\/2022\/10\/planivolumetrico-esec.jpg 1386w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><\/div><div class=\"w-separator size_medium with_line width_default thick_1 style_solid color_border align_center\"><div class=\"w-separator-h\"><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"[vc_custom_heading text=\"NUOVE COSTRUZIONI - ZONA INFERNETTO ROMA\" font_container=\"tag:h1|font_size:43|text_align:center|color:%23ffffff\" google_fonts=\"font_family:Alef%3Aregular%2C700|font_style:400%20regular%3A400%3Anormal\" css=\"%7B%22default%22%3A%7B%22color%22%3A%22%23ffffff%22%7D%7D\"][vc_custom_heading text=\"Via Alberto Franchetti\" font_container=\"tag:h4|font_size:28|text_align:center|color:%236b6b6b\" google_fonts=\"font_family:Abel%3Aregular|font_style:400%20regular%3A400%3Anormal\" css=\"%7B%22default%22%3A%7B%22color%22%3A%22%23e8e8e8%22%2C%22margin-top%22%3A%22-40px%22%7D%7D\"] [vc_custom_heading text=\"Il Piano di Zona Infernetto Nord si attesta nell\u2019ultima area libera prima del settore settentrionale della tenuta presidenziale di Castel Porziano, in una zona di particolare interesse ambientale aderente alla via Cristoforo Colombo.\" font_container=\"tag:h4|font_size:22|text_align:left\" google_fonts=\"font_family:Abel%3Aregular|font_style:400%20regular%3A400%3Anormal\"][vc_custom_heading text=\"Il progetto \u00e8...","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-526","page","type-page","status-publish","hentry"],"acf":[],"_links":{"self":[{"href":"https:\/\/ambientecooperative.it\/infernetto-nord\/wp-json\/wp\/v2\/pages\/526","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ambientecooperative.it\/infernetto-nord\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/ambientecooperative.it\/infernetto-nord\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/ambientecooperative.it\/infernetto-nord\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ambientecooperative.it\/infernetto-nord\/wp-json\/wp\/v2\/comments?post=526"}],"version-history":[{"count":17,"href":"https:\/\/ambientecooperative.it\/infernetto-nord\/wp-json\/wp\/v2\/pages\/526\/revisions"}],"predecessor-version":[{"id":1123,"href":"https:\/\/ambientecooperative.it\/infernetto-nord\/wp-json\/wp\/v2\/pages\/526\/revisions\/1123"}],"wp:attachment":[{"href":"https:\/\/ambientecooperative.it\/infernetto-nord\/wp-json\/wp\/v2\/media?parent=526"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}